{"id":701,"date":"2025-07-02T10:12:27","date_gmt":"2025-07-02T10:12:27","guid":{"rendered":"https:\/\/tjt.travelblox.eu\/?p=701"},"modified":"2026-04-30T13:21:51","modified_gmt":"2026-04-30T13:21:51","slug":"que-faire-en-jordanie-activites-et-experiences-incontournables","status":"publish","type":"post","link":"https:\/\/tjt.travelblox.eu\/fr\/que-faire-en-jordanie-activites-et-experiences-incontournables\/","title":{"rendered":"Que faire en Jordanie : activit\u00e9s et exp\u00e9riences \u00e0 ne pas manquer."},"content":{"rendered":"<div class=\"tb-wysiwyg tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"wysiwyg\">\n    <div class=\"inner-block\">\n        <div class=\"tb-wysiwyg__inner tb-wysiwyg__inner--highlight\">\n            <div class=\"inner-block\">\n                                    <!-- <div class=\"icon\">\n                    <img decoding=\"async\" src=\"\/var\/www\/prod\/public_html\/wp-content\/plugins\/tbx-plugin\/blox\/wysiwyg\/..\/..\/images\/wave-1.php \" alt=\"Lamp icon\"\/>\n                <\/div> -->\n                    <div class=\"icon\">\n                        <i class=\"fa-kit fa-tb-lightbulb\"><\/i>\n                    <\/div>\n                                <div class=\"text-part wysiwyg\">\n                                            <h4>Les conseils de l'\u00e9quipe<\/h4>                                        \t<div class=\"translation-block\"><p>La <strong>Jordanie<\/strong> est une terre de d\u00e9couvertes o\u00f9 chaque voyageur trouve son bonheur, du passionn\u00e9 d\u2019histoire \u00e0 l\u2019aventurier dans l\u2019\u00e2me. Pour saisir toute la richesse du pays, accordez-vous <strong>au moins une semaine<\/strong> sur place. Notre <strong>meilleur conseil<\/strong> ? <strong>Alternez<\/strong> les <strong>visites des grands sites<\/strong> avec des <strong>moments plus authentiques<\/strong> : randonn\u00e9e dans des vall\u00e9es pr\u00e9serv\u00e9es, nuit dans un camp b\u00e9douin traditionnel, ou d\u00e9couverte de la cuisine locale. Ce sont ces <strong>instants de partage avec les habitants<\/strong> qui transforment un simple voyage en une aventure m\u00e9morable.<\/p><\/div>\n\t                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"tb-wysiwyg tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"wysiwyg-1\">\n    <div class=\"inner-block\">\n        <div class=\"tb-wysiwyg__inner\">\n            <div class=\"inner-block\">\n                                <div class=\"text-part wysiwyg\">\n                                            <h2>Que faire en Jordanie : activit\u00e9s et exp\u00e9riences \u00e0 ne pas manquer.<\/h2>                                                                \t<div class=\"translation-block\"><p><span style=\"font-weight: 400\">La Jordanie offre un <strong>m\u00e9lange unique<\/strong> d'histoire mill\u00e9naire et d'aventures en pleine nature. Ce pays du Moyen-Orient s\u00e9duit autant par son <strong>patrimoine exceptionnel<\/strong> que par la <strong>diversit\u00e9 de ses paysages<\/strong>, des d\u00e9serts aux montagnes en passant par la mer Rouge. Voici les <strong>exp\u00e9riences<\/strong> qui rendront votre s\u00e9jour m\u00e9morable.<\/span><\/p><\/div>\n\t                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"tb-cta-banner tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"cta-banner\">\n    <div class=\"inner-block\">\n        <a href=\"https:\/\/thejordantrail.org\/fr\/\" class=\"tb-cta-banner__link\" target=\"_blank\" title=\"\">\n            <div class=\"icon\"><i class=\"fa-solid fa-arrow-right\"><\/i><\/div>\n            <div class=\"text-part\">\n                                    <strong>D\u00e9couvrez le Jordan Trail !<\/strong>\n                                                    <span>Un trek de 5 jours jusqu'\u00e0 P\u00e9tra <\/span>\n                            <\/div>\n        <\/a>\n    <\/div>\n<\/div>\n\n\n<div class=\"tb-image tb-block align-none background-light pattern-none variant-none\" id=\"image\">\n\t<figure>\n\t\t\t\t<img src='https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/Jordanie-4.jpeg.webp' width='1024' height='683' alt='canyon Jordanie' srcset='https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/Jordanie-4.jpeg.webp 1024w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/Jordanie-4-300x200.jpeg.webp 300w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/Jordanie-4-768x512.jpeg.webp 768w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/Jordanie-4-18x12.jpeg.webp 18w' sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/Jordanie-4.jpeg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/Jordanie-4.jpeg 1024w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/Jordanie-4-300x200.jpeg 300w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/Jordanie-4-768x512.jpeg 768w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/Jordanie-4-18x12.jpeg 18w&quot;}\">\t\t\t\t\t<\/figure>\n<\/div>\n\n\n<div class=\"tb-wysiwyg tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"wysiwyg-2\">\n    <div class=\"inner-block\">\n        <div class=\"tb-wysiwyg__inner\">\n            <div class=\"inner-block\">\n                                <div class=\"text-part wysiwyg\">\n                                                                                                            \t<div class=\"translation-block\"><h2><b>Faire un trek en Jordanie : l\u2019aventure \u00e0 l\u2019\u00e9tat pur<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Les <strong>sentiers mill\u00e9naires<\/strong> qui serpentent \u00e0 travers les montagnes et le d\u00e9sert jordanien offrent un terrain id\u00e9al pour la randonn\u00e9e. <a href=\"https:\/\/thejordantrail.org\/fr\/\">Notre Jordan Trail<\/a>, de Shobak \u00e0 P\u00e9tra, vous fait d\u00e9couvrir des paysages spectaculaires, loin des circuits touristiques classiques. <strong>Au programme<\/strong> : canyons aux parois color\u00e9es, passages historiques emprunt\u00e9s par les anciennes caravanes, et nuits en pleine nature sous un ciel \u00e9toil\u00e9 remarquable. Cette randonn\u00e9e en Jordanie vous permet de <strong>d\u00e9couvrir des<\/strong> <strong>villages authentiques<\/strong> et de <strong>rencontrer leurs habitants<\/strong>, avant d\u2019arriver \u00e0 Petra, Jordanie, par un itin\u00e9raire pr\u00e9serv\u00e9.<\/span><\/p>\n<h2><b>Dormir dans le d\u00e9sert du Wadi Rum<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Le <strong>Wadi Rum<\/strong> offre une exp\u00e9rience authentique du d\u00e9sert. Les <strong>camps b\u00e9douins<\/strong> proposent diff\u00e9rentes options d\u2019h\u00e9bergement, des tentes traditionnelles aux installations plus modernes avec vue sur le ciel \u00e9toil\u00e9. La soir\u00e9e commence g\u00e9n\u00e9ralement par <strong>une excursion en 4\u00d74<\/strong> pour admirer le coucher du soleil, suivie d\u2019un th\u00e9 \u00e0 la sauge pr\u00e9par\u00e9 sur le feu. <strong>Le d\u00eener traditionnel<\/strong>, pr\u00e9par\u00e9 dans le sable selon les coutumes locales, permet de d\u00e9couvrir la cuisine b\u00e9douine. En soir\u00e9e, vous pouvez profiter de musique traditionnelle avant <strong>une nuit sous les \u00e9toiles<\/strong>.<\/span><\/p><\/div>\n\t                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"tb-cta-banner tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"cta-banner-1\">\n    <div class=\"inner-block\">\n        <a href=\"https:\/\/travelbase.fr\/trip\/jordanie-trek-petra\/\" class=\"tb-cta-banner__link\" target=\"_blank\" title=\"\">\n            <div class=\"icon\"><i class=\"fa-solid fa-arrow-right\"><\/i><\/div>\n            <div class=\"text-part\">\n                                    <strong>Pour d\u00e9couvrir la Jordanie en trek, essaie le Jordan Trail ! \u26fa\ufe0f<\/strong>\n                                                    <span>Un trek de 5 jours jusqu'\u00e0 la l\u00e9gendaire P\u00e9tra.<\/span>\n                            <\/div>\n        <\/a>\n    <\/div>\n<\/div>\n\n\n<div class=\"tb-image tb-block align-none background-light pattern-none variant-none\" id=\"image-1\">\n\t<figure>\n\t\t\t\t<img src='https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2024\/01\/theJordanTrail-5306-scaled-e1705659718218.jpg.webp' width='800' height='533' alt='Ciel \u00e9toil\u00e9 - Le Sentier de Jordanie' loading='lazy' decoding='async' data-smush-webp-fallback='{&quot;src&quot;:&quot;https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2024\\\/01\\\/theJordanTrail-5306-scaled-e1705659718218.jpg&quot;}'>\t\t\t\t\t<\/figure>\n<\/div>\n\n\n<div class=\"tb-wysiwyg tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"wysiwyg-3\">\n    <div class=\"inner-block\">\n        <div class=\"tb-wysiwyg__inner\">\n            <div class=\"inner-block\">\n                                <div class=\"text-part wysiwyg\">\n                                                                                                            \t<div class=\"translation-block\"><h2><b>Flotter dans la Mer Morte<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Cette \u00e9tendue d'eau hyper sal\u00e9e, point le plus bas du globe \u00e0 430 m\u00e8tres sous le niveau de la mer, offre une <strong>exp\u00e9rience de baignade unique<\/strong>. Les visiteurs peuvent profiter des propri\u00e9t\u00e9s naturelles de l'eau et de la boue riche en min\u00e9raux, r\u00e9put\u00e9e pour ses bienfaits. La forte concentration en sel permet de <strong>flotter sans effort<\/strong> \u2013 une sensation particuli\u00e8re qui m\u00e9rite le d\u00e9tour. Les complexes h\u00f4teliers du littoral proposent \u00e9galement des <strong>soins spa<\/strong> utilisant les propri\u00e9t\u00e9s de cette eau unique.<\/span><\/p>\n<h2><b>Explorer P\u00e9tra de nuit<\/b><\/h2>\n<p><span style=\"font-weight: 400\">L'exp\u00e9rience \u201cP\u00e9tra by Night\u201d propose une <strong>d\u00e9couverte diff\u00e9rente<\/strong> du site historique. Trois soirs par semaine, le Siq est \u00e9clair\u00e9 par des <strong>centaines de bougies<\/strong> qui cr\u00e9ent une atmosph\u00e8re particuli\u00e8re. La marche de 2 kilom\u00e8tres dans ce passage illumin\u00e9 m\u00e8ne au Tr\u00e9sor (Al-Khazneh), mis en valeur par les lumi\u00e8res. Un moment de <strong>musique traditionnelle<\/strong> b\u00e9douine et des <strong>r\u00e9cits locaux<\/strong> compl\u00e8tent la visite.<\/span><\/p>\n<h2><b>Cuisiner avec les locaux<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Les cours de cuisine permettent une <strong>immersion dans la culture jordanienne<\/strong>. G\u00e9n\u00e9ralement organis\u00e9s dans des maisons traditionnelles, ils vous initient \u00e0 la pr\u00e9paration des <strong>sp\u00e9cialit\u00e9s locales<\/strong> comme le <strong>mansaf<\/strong> (plat national), les <strong>mezze<\/strong> vari\u00e9s et les <strong>feuilles de vigne farcies<\/strong>. Vous d\u00e9couvrez les \u00e9pices locales, les techniques de cuisson traditionnelles et la pr\u00e9paration du caf\u00e9 et du th\u00e9 \u00e0 la menthe. Le cours se termine par un <strong>repas convivial<\/strong> o\u00f9 vous d\u00e9gustez vos pr\u00e9parations.<\/span><\/p><\/div>\n\t                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"tb-cta-banner tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"cta-banner-2\">\n    <div class=\"inner-block\">\n        <a href=\"https:\/\/travelbase.fr\/trip\/jordanie-trek-petra\/\" class=\"tb-cta-banner__link\" target=\"_blank\" title=\"\">\n            <div class=\"icon\"><i class=\"fa-solid fa-arrow-right\"><\/i><\/div>\n            <div class=\"text-part\">\n                                    <strong>Lors du Jordan Trail, vous avez la possibilit\u00e9 de choisir des repas pr\u00e9par\u00e9s avec amour par les habitants.<\/strong>\n                                                    <span>Un moment convivial et de partage !<\/span>\n                            <\/div>\n        <\/a>\n    <\/div>\n<\/div>\n\n\n<div class=\"tb-image tb-block align-none background-light pattern-none variant-none\" id=\"image-2\">\n\t<figure>\n\t\t\t\t<img src='https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1.jpeg.webp' width='2560' height='1708' alt='mer morte Jordanie' srcset='https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1.jpeg.webp 2560w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-300x200.jpeg.webp 300w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-1024x683.jpeg.webp 1024w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-768x512.jpeg.webp 768w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-1536x1025.jpeg.webp 1536w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-18x12.jpeg.webp 18w' sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1.jpeg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1.jpeg 2560w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-300x200.jpeg 300w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-1024x683.jpeg 1024w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-768x512.jpeg 768w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-1536x1025.jpeg 1536w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_R5SG9260-1-18x12.jpeg 18w&quot;}\">\t\t\t\t\t<\/figure>\n<\/div>\n\n\n<div class=\"tb-wysiwyg tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"wysiwyg-4\">\n    <div class=\"inner-block\">\n        <div class=\"tb-wysiwyg__inner\">\n            <div class=\"inner-block\">\n                                <div class=\"text-part wysiwyg\">\n                                                                                                            \t<div class=\"translation-block\"><h2><b>Faire de la plong\u00e9e dans la Mer Rouge<\/b><\/h2>\n<p><span style=\"font-weight: 400\"><strong>Aqaba<\/strong> offre plusieurs sites de plong\u00e9e adapt\u00e9s \u00e0 tous les niveaux. Les r\u00e9cifs coralliens abritent une <strong>riche biodiversit\u00e9<\/strong> avec de nombreuses esp\u00e8ces de <strong>poissons<\/strong>, des <strong>tortues<\/strong> marines et parfois des <strong>dauphins<\/strong>. Pour les amateurs d'histoire, plusieurs \u00e9paves, dont un char d'assaut et un cargo, constituent des sites de plong\u00e9e int\u00e9ressants. La <strong>bonne visibilit\u00e9<\/strong> (souvent sup\u00e9rieure \u00e0 30 m\u00e8tres) et la <strong>temp\u00e9rature agr\u00e9able<\/strong> de l'eau en font une destination appr\u00e9ci\u00e9e des plongeurs.<\/span><\/p>\n<h2><b>Suivre la Route des Rois<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Cette <strong>route historique<\/strong>, utilis\u00e9e depuis plus de 3000 ans, traverse des paysages remarquables de Jordanie. C'est le chemin qu'emprunte notre trek en Jordanie, permettant de suivre les traces des marchands nabat\u00e9ens. Le parcours offre des points de vue sur la vall\u00e9e du Rift et la Mer Morte, passe par des villages traditionnels et des sites historiques importants comme le Mont N\u00e9bo.<\/span><\/p><\/div>\n\t                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"tb-image tb-block align-none background-light pattern-none variant-none\" id=\"image-3\">\n\t<figure>\n\t\t\t\t<img src='https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-scaled.jpeg.webp' width='2560' height='1708' alt='voiture sur une route au milieu du d\u00e9sert lors d&#039;un road trip en Jordanie' srcset='https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-scaled.jpeg.webp 2560w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-300x200.jpeg.webp 300w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-1024x683.jpeg.webp 1024w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-768x512.jpeg.webp 768w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-1536x1025.jpeg.webp 1536w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-2048x1366.jpeg.webp 2048w, https:\/\/tjt.travelblox.eu\/wp-content\/smush-webp\/sites\/78\/2025\/01\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-18x12.jpeg.webp 18w' sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" loading='lazy' decoding='async' data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-scaled.jpeg&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-scaled.jpeg 2560w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-300x200.jpeg 300w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-1024x683.jpeg 1024w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-768x512.jpeg 768w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-1536x1025.jpeg 1536w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-2048x1366.jpeg 2048w, https:\\\/\\\/tjt.travelblox.eu\\\/wp-content\\\/uploads\\\/sites\\\/78\\\/2025\\\/01\\\/JORDAN_NOMADS_SJOERDBRACKE_387A1000-18x12.jpeg 18w&quot;}\">\t\t\t\t\t<\/figure>\n<\/div>\n\n\n<div class=\"tb-wysiwyg tb-block align-left background-light pattern-none variant-none tb-collapsible-margins\" id=\"wysiwyg-5\">\n    <div class=\"inner-block\">\n        <div class=\"tb-wysiwyg__inner\">\n            <div class=\"inner-block\">\n                                <div class=\"text-part wysiwyg\">\n                                                                                                            \t<div class=\"translation-block\"><h2><b>Observer les oiseaux \u00e0 Azraq<\/b><\/h2>\n<p><span style=\"font-weight: 400\">La r\u00e9serve d'Azraq est une \u00e9tape cl\u00e9 pour les oiseaux migrateurs entre l'Afrique et l'Europe. Cette oasis au c\u0153ur du d\u00e9sert oriental abrite plus de 300 esp\u00e8ces d'oiseaux selon les saisons. Des observatoires bien situ\u00e9s et des guides naturalistes facilitent l'observation et l'identification des esp\u00e8ces. Les premi\u00e8res heures du jour offrent les meilleures conditions d'observation.<\/span><\/p>\n<h2><b>Admirer les mosa\u00efques de Madaba<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Madaba, connue comme la \"Ville des Mosa\u00efques\", abrite d'importantes \u0153uvres d'art byzantin. La plus c\u00e9l\u00e8bre est la carte-mosa\u00efque de la Terre Sainte du VIe si\u00e8cle dans l'\u00e9glise Saint-Georges. La ville compte plusieurs sites remarquables : l'\u00e9glise des Ap\u00f4tres, le parc arch\u00e9ologique et des maisons traditionnelles d\u00e9cor\u00e9es. Des ateliers locaux perp\u00e9tuent cet artisanat et proposent des d\u00e9monstrations.<\/span><\/p>\n<h2><b>Se ressourcer aux sources chaudes de Ma'in<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Les chutes d'eau chaude de Ma'in, situ\u00e9es pr\u00e8s d'Amman, offrent un moment de d\u00e9tente naturel. Ces cascades, chauff\u00e9es naturellement \u00e0 environ 40\u00b0C, sont appr\u00e9ci\u00e9es pour leurs propri\u00e9t\u00e9s min\u00e9rales. Le site combine des installations modernes et des zones plus naturelles, permettant de profiter des bienfaits de ces eaux thermales dans diff\u00e9rents cadres.<\/span><\/p><\/div>\n\t                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":134,"featured_media":783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","team-member-jimmy-de-travelbase","blog-category-activities"],"acf":{"testing_rest":""},"_links":{"self":[{"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/posts\/701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/comments?post=701"}],"version-history":[{"count":16,"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/posts\/701\/revisions"}],"predecessor-version":[{"id":1615,"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/posts\/701\/revisions\/1615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/media\/783"}],"wp:attachment":[{"href":"https:\/\/tjt.travelblox.eu\/fr\/wp-json\/wp\/v2\/media?parent=701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}